{"id":1653,"date":"2018-06-29T01:32:51","date_gmt":"2018-06-28T23:32:51","guid":{"rendered":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/?p=1653"},"modified":"2018-06-29T01:32:51","modified_gmt":"2018-06-28T23:32:51","slug":"avis-importants-pour-tous","status":"publish","type":"post","link":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/avis-importants-pour-tous\/","title":{"rendered":"Avis importants pour tous"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1654\" src=\"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-content\/uploads\/2018\/06\/depositphotos_21118229-stockafbeelding-bagage-dat-bestaat-uit-grote-300x243.jpg\" alt=\"\" width=\"300\" height=\"243\" srcset=\"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-content\/uploads\/2018\/06\/depositphotos_21118229-stockafbeelding-bagage-dat-bestaat-uit-grote-300x243.jpg 300w, https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-content\/uploads\/2018\/06\/depositphotos_21118229-stockafbeelding-bagage-dat-bestaat-uit-grote.jpg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/strong>Avant de faire le mauvais parcours \u00e0 Fatima, voir ici les AVIS IMPORTANTS que l&#8217;\u00e9quipe d&#8217;organisation a pour vous!<\/p>\n<p>Il y a les <strong>avertissements g\u00e9n\u00e9raux<\/strong>, les <strong>avertissements du clerg\u00e9<\/strong> et les <strong>avertissements pour ceux qui ont besoin de transport.<\/strong><\/p>\n<p>Voir tout ci-dessous &#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>1 \u2013 ANNONCES G\u00c9N\u00c9RALES<\/u><\/strong><strong>:<\/strong><\/p>\n<ul>\n<li>Comme pour tout voyage, si vous souhaitez souscrire une <u>assurance voyage<\/u> pour plus de commodit\u00e9, vous devez la souscrire \u00e0 titre personnel\u00a0; l\u2019Organisation du Rassemblement Fatima 2018 ne pourra pas se responsabiliser concernant des d\u00e9penses d\u2019assistance en voyage, sant\u00e9, rapatriement, etc\u2026<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Prenez soin d\u2019identifier vos bagages avec une <u>\u00e9tiquette ayant n\u00ba, nom et adresse de l\u2019h\u00f4tel \/h\u00e9bergement de s\u00e9jour<\/u>, afin d\u2019\u00e9viter les pertes et de faciliter \u00e9ventuellement la r\u00e9cup\u00e9ration.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Il est tr\u00e8s important <u>de se faire accompagner du voucher<\/u> afin de le pr\u00e9senter lors du premier contact avec l\u2019Organisation du Rassemblement, que ce soit<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ol>\n<li>\u00e0 Fatima, directement dans les h\u00f4tels, pour ceux qui arrivent par leurs propres moyens ou avec les Super-R\u00e9gion\u00a0;<\/li>\n<li>\u00e0 l\u2019a\u00e9roport de Lisbonne ou Porto, et a demand\u00e9 des transports pour F\u00e1tima lors de l\u2019inscription\u00a0;<\/li>\n<li>ou, pour ceux qui se soient arriv\u00e9s au Portugal quelques jours avant, dans tous les points rencontre des villes o\u00f9 il existe des informations pour se rencontrer le 16 Juillet, \u00e0 l\u2019heure convenue, pour prendre le bus pour Fatima.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le 16 Juillet sera la Journ\u00e9e d\u2019Accueil \u00e0 F\u00e1tima dans les h\u00f4tels et h\u00e9bergements. Le premier repas \u00e9tant servi \u00e0 partir de 19h00, il est tr\u00e8s important de s\u2019installer \u00e0 l\u2019h\u00f4tel (chek in) <u>le plus rapidement possible<\/u> afin d\u2019\u00e9viter les files de fin d\u2019apr\u00e8s-midi. Nous comptons sur votre collaboration.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>A l\u2019h\u00f4tel, vous recevrez un Kit avec divers mat\u00e9riel et documentation que vous pourrez lire attentivement. La premi\u00e8re chose \u00e0 faire \u00e9tant de s\u2019\u00e9quiper d\u2019un <u>badge d\u2019identification<\/u> et de <u>prendre le ticket repas pour le d\u00eener<\/u> du 16 Juillet.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Dans le Kit distribu\u00e9 \u00e0 chaque couple et Conseiller Spirituel, vous trouverez le <strong><u>Guide du Participant<\/u>, \u00e0 lire attentivement<\/strong> d\u00e8s l\u2019arriv\u00e9e car il contient des rappels et des recommandations importantes concernant tous les moments du Rassemblement. Le Guide Liturgique se trouve dans le m\u00eame livre, du c\u00f4t\u00e9 oppos\u00e9.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le d\u00eener, servi sur pr\u00e9sentation du ticket repas que vous trouverez dans le Kit, doit \u00eatre pris rapidement afin de se rendre au lieu de rendez de vous de la <strong><u>Cruz Alta \u00e0 20h30<\/u><\/strong> (indiqu\u00e9 sur la carte) avec les <u>badges et les foulards<\/u> de couleur au cou (faisant partie du Kit) afin de pouvoir commencer la tant attendue c\u00e9r\u00e9monie d\u2019Ouverture. Si possible, anticiper votre arriv\u00e9e \u00e0 Cruz Alta.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nous rappelons que pour diverses raisons, notamment de s\u00e9curit\u00e9, <strong><u>personne ne pourra rentrer dans la Basilique de la Sainte Trinit\u00e9 pour assister \u00e0 la c\u00e9r\u00e9monie d\u2019ouverture sans le badge d\u2019identification<\/u><\/strong>. Ce badge est individuel et devra \u00eatre port\u00e9 par chaque participant du premier au dernier jour du Rassemblement.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>D\u00e8s la c\u00e9r\u00e9monie d\u2019ouverture du Rassemblement, les horaires seront scrupuleusement respect\u00e9s, raison pour laquelle nous demandons \u00e0 tous un effort de <strong><u>ponctualit\u00e9<\/u><\/strong>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>2 &#8211; ANNONCES POUR LE CLERG\u00c9<\/u><\/strong><\/p>\n<p>2.1.\u00a0\u00a0\u00a0 Tous les ministres ordonn\u00e9s doivent apporter \u00e0 Fatima leur carte d&#8217;identit\u00e9 (<em>celebret<\/em>) afin d&#8217;\u00eatre reconnus comme tels.<\/p>\n<p>&nbsp;<\/p>\n<p>2.2.\u00a0\u00a0\u00a0 Les pr\u00eatres et les diacres doivent apporter une aube et un cordon.<\/p>\n<p>&nbsp;<\/p>\n<p>2.3.\u00a0\u00a0\u00a0 Dans le Kit distribu\u00e9 dans les h\u00f4tels, tous les ministres ordonn\u00e9s recevront une \u00e9tole blanche avec le symbole du Rassemblement qui sera utilis\u00e9e dans toutes les c\u00e9l\u00e9brations liturgiques.<\/p>\n<p>&nbsp;<\/p>\n<p>2.4.\u00a0\u00a0\u00a0 Les \u00e9toles seront toutes \u00e9gales et indistinctes, donc les diacres doivent faire l\u2019adaptation avec une \u00e9pingle qu\u2019ils doivent apporter pour cet effet.<\/p>\n<p>&nbsp;<\/p>\n<p>2.5.\u00a0\u00a0\u00a0 Le sanctuaire de Fatima fournira aux \u00e9v\u00eaques les ornements liturgiques n\u00e9cessaires pour les diff\u00e9rentes c\u00e9l\u00e9brations durant le Rassemblement.<\/p>\n<p>&nbsp;<\/p>\n<p>2.6.\u00a0\u00a0\u00a0 Le premier jour, le 16 juillet, pour la c\u00e9r\u00e9monie d&#8217;ouverture du Rassemblement, il ne sera pas n\u00e9cessaire que les ministres ordonn\u00e9s prennent l\u2019aube et l\u2019\u00e9tole, puisque la c\u00e9r\u00e9monie n&#8217;inclut pas une c\u00e9l\u00e9bration liturgique.<\/p>\n<p>&nbsp;<\/p>\n<p>2.7.\u00a0\u00a0\u00a0 Les autres jours du Rassemblement, il y aura toujours l\u2019Eucharistie, aux heures d\u00e9finies dans le programme distribu\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>2.8.\u00a0\u00a0\u00a0 C\u2019est \u00e0 la Basilique de la Sainte Trinit\u00e9 qui aura lieu la plupart des activit\u00e9s du Rassemblement et, \u00e0 l&#8217;exception de la c\u00e9r\u00e9monie de cl\u00f4ture le 21 juillet, toutes les c\u00e9l\u00e9brations eucharistiques y seront c\u00e9l\u00e9br\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p>2.9.\u00a0\u00a0\u00a0 Le presbyt\u00e8re de la Basilique de la Sainte Trinit\u00e9 ne compte que 120 si\u00e8ges, donc, parmi les 400 presbytres qui conc\u00e9l\u00e8breront \u00e0 chaque c\u00e9l\u00e9bration, seulement pr\u00e8s de 100 pourront s\u2019assoir dans le presbyt\u00e8re, \u00e0 c\u00f4t\u00e9 des \u00e9v\u00eaques. Les autres seront assis dans la premi\u00e8re rang\u00e9e de l&#8217;assembl\u00e9e comme indiqu\u00e9 par le service d\u2019ordre.<\/p>\n<p>&nbsp;<\/p>\n<p>2.10.\u00a0 On indiquera \u00e0 chaque pr\u00eatre le jour et la c\u00e9l\u00e9bration o\u00f9 il pourra, si possible, s\u2019assoir au presbyt\u00e8re. Durant la semaine du Rassemblement, nous essaierons de faire asseoir tous les pr\u00eatres au presbyt\u00e8re au moins pour une c\u00e9l\u00e9bration eucharistique. Cependant il n&#8217;est pas garanti que cela soit possible, en fonction du nombre d&#8217;\u00e9v\u00eaques pr\u00e9sents dans chaque c\u00e9l\u00e9bration.<\/p>\n<p>&nbsp;<\/p>\n<p>2.11.\u00a0 Tous les ministres ordonn\u00e9s doivent se rassembler dans la sacristie, pour mettre leurs ornements liturgiques, 15 minutes avant les c\u00e9l\u00e9brations. Ceux qui ne respectent pas ce d\u00e9lai n&#8217;auront pas l&#8217;acc\u00e8s garanti au presbyt\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<p>2.12.\u00a0 Seuls les ministres ordonn\u00e9s qui ont une place au presbyt\u00e8re feront partie de la procession d&#8217;entr\u00e9e. Les autres devront commencer \u00e0 entrer dans la Basilique 15 minutes avant la c\u00e9l\u00e9bration, embrasser l&#8217;autel et ensuite se diriger vers les premi\u00e8res rang\u00e9es de l&#8217;assembl\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p>2.13.\u00a0 Lors des c\u00e9l\u00e9brations, la forme ordinaire du rite romain sera toujours utilis\u00e9e. Tous les pr\u00eatres doivent apporter leur propre missel afin de pouvoir accompagner les parties communes de la Messe.<\/p>\n<p>&nbsp;<\/p>\n<p>2.14.\u00a0 La derni\u00e8re c\u00e9l\u00e9bration liturgique, le 21 juillet, jour de la cl\u00f4ture du Rassemblement, sera c\u00e9l\u00e9br\u00e9e au Sanctuaire. Ce jour-l\u00e0, les ministres ordonn\u00e9s doivent se pr\u00e9senter au plus tard \u00e0 10h15, derri\u00e8re la chapelle des apparitions, pour avoir acc\u00e8s au sanctuaire et ainsi pouvoir participer \u00e0 la procession et \u00e0 la c\u00e9l\u00e9bration de l&#8217;Eucharistie. Ils doivent apporter avec eux les aubes, les cordons et les \u00e9toles qu\u2019ils utiliseront durant la c\u00e9l\u00e9bration.<\/p>\n<p>&nbsp;<\/p>\n<p>2.15.\u00a0 Lors de la veill\u00e9e d&#8217;adoration du 19 au 20 juillet (du jeudi au vendredi), il est n\u00e9cessaire de garantir le service de confession dans la basilique de Notre-Dame du Rosaire, \u00e0 partir de 23h00 et pendant toute la nuit. Nous prions les pr\u00eatres de se rendre disponibles pour confesser, dans les langues possibles, avec la g\u00e9n\u00e9rosit\u00e9 de ceux qui administrent les dons de Dieu.<\/p>\n<p>&nbsp;<\/p>\n<p>2.16. En outre, pendant le Rassemblement il est recommand\u00e9 que les pr\u00eatres \u00e0 qui on demande de donner le sacrement de la r\u00e9conciliation, le fassent sans pr\u00e9judice de la dynamique g\u00e9n\u00e9rale du Rassemblement.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>3 \u2013Pour ceux qui ont demand\u00e9 un transport vers FATIMA <\/u><\/strong><\/p>\n<ul>\n<li>Les demandes de transport organis\u00e9 de Fatima vers d\u2019autres villes devront \u00eatre faites de fa\u00e7on anticip\u00e9e et seront prises en compte apr\u00e8s enregistrement de la demande para l\u2019Equipe Organisatrice.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour b\u00e9n\u00e9ficier du transport vers Fatima \u00e0 partir des villes o\u00f9 les participants se trouvent, Lisbonne ou Porto, il sera n\u00e9cessaire de pr\u00e9senter le voucher o\u00f9 se trouveront toutes les informations concernant le transfert.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><u>TR\u00c8S IMPORTANT\u00a0: Le voucher devra \u00eatre imprim\u00e9 sur papier<\/u> (avant le d\u00e9part). Il ne sera pas possible d\u2019imprimer sur place dans les lieux de d\u00e9parts des bus.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour ceux qui arrivent au Portugal le 16 Juillet par avion ou train, il y aura, dans les diff\u00e9rents a\u00e9roports ou gares, des membres de l\u2019Equipe organisatrice qui indiqueront le chemin vers les diff\u00e9rents bus.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour ceux qui arrivent au Portugal avant le 16 Juillet, le d\u00e9part vers Fatima se fera le 16 Juillet au lieu et heure indiqu\u00e9es sur le voucher (villes de Lisbonne ou Porto), o\u00f9 se trouveront des membres de l\u2019Equipe organisatrice, d\u00fbment identifi\u00e9es, qui aideront les participants \u00e0 prendre les diff\u00e9rents bus vers Fatima.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><u>TR\u00c8S IMPORTANT\u00a0<\/u>: les lieux et heures de d\u00e9part de chaque bus vers Fatima d\u00e9pendent du lieu d\u2019h\u00e9bergement de chaque participant, raison pour laquelle ces informations peuvent diff\u00e9rer de celles d\u2019autres couples. <u>Suivez rigoureusement les indications de lieu et horaire de d\u00e9part inscrites sur votre voucher.<\/u><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>L\u2019Equipe organisatrice ne <u>pourra pas assurer le transport vers Fatima<\/u> en cas de retard des participants.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour les participants arrivant par train \u00e0 Lisbonne ou Porto, lisez attentivement le voucher pour savoir o\u00f9 prendre le bus: il pourra \u00eatre n\u00e9cessaire \u00e0 <u>certains horaires<\/u> de devoir prendre les transports publiques (ex. le m\u00e9tro) pour rejoindre l\u2019a\u00e9roport de la ville o\u00f9 se trouve le d\u00e9part des bus \u00e0 destination de Fatima.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>L\u2019entr\u00e9e dans le bus vers Fatima se fera \u00e0 l\u2019aide du code barre du voucher de fa\u00e7on \u00e0 identifier le participant et son lieu de destination. Veuillez garder votre voucher \u00e0 port\u00e9e de main pour faciliter l\u2019entr\u00e9e dans le bus.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>A l\u2019arriv\u00e9e \u00e0 Fatima, le bus s\u2019arr\u00eatera dans un parc proche du Centre Paul VI\u00a0; un membre de l\u2019Equipe organisatrice se joindra au bus afin d\u2019aider les participants \u00e0 rejoindre leurs h\u00f4tels\/h\u00e9bergement.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Les participants ne devront sortir du bus qu\u2019au moment de l\u2019arriv\u00e9e \u00e0 leurs h\u00f4tels\/h\u00e9bergement respectifs.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>4 \u2013Pour ceux qui ont demand\u00e9 un transport de FATIMA VERS D\u2019AUTRES VILLES\u00a0 le dernier jour <\/u><\/strong><\/p>\n<ul>\n<li>Les demandes de transport organis\u00e9 de Fatima vers d\u2019autres villes devront \u00eatre faites de fa\u00e7on anticip\u00e9e et seront prises en compte apr\u00e8s enregistrement de la demande par l\u2019Equipe Organisatrice.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le num\u00e9ro et heure de d\u00e9part du bus de Fatima vers Lisbonne ou Porto se trouvera inscrit au verso du badge de chaque participant.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>La pr\u00e9sentation du badge sera suffisante mais indispensable pour autoriser l\u2019entr\u00e9e dans le bus au d\u00e9part de Fatima.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour les personnes qui quittent Fatima le 21 JUILLET AVANT 8H30: soyez attentifs aux instructions du couple responsable la veille du d\u00e9part\u00a0; celles-ci seront \u00e9galement affix\u00e9es au placard de chaque h\u00e9bergement le 20 Juillet.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pour les personnes qui quittent Fatima le 21 JUILLET APRES 8H30: le d\u00e9part des bus se fera au parc 12 du Sanctuaire, proche du Centre Paul VI o\u00f9 se trouvera la tente de l\u2019Expo. Les voyageurs pourront emprunter les transports qui circuleront en interne \u00e0 Fatima, conform\u00e9ment aux informations fix\u00e9es sur les placards de l\u2019h\u00f4tel.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>La maille de r\u00e9seau de transports internes de Fatima sera modifi\u00e9e le dernier jour pour faciliter le d\u00e9placement des participants avec bagages vers le lieu de d\u00e9part des bus (voir point pr\u00e9c\u00e9dent). Ainsi il est important de v\u00e9rifier sur les placards de l\u2019h\u00f4tel\/h\u00e9bergement la carte mise \u00e0 jour des transports avec les nouvelles lignes de circulation.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Au parc 12 du Sanctuaire de F\u00e1tima, tous les bus seront num\u00e9rot\u00e9s et il y aura des membres de l\u2019\u00c9quipe Organisatrice qui pourront aider les participants \u00e0 identifier leurs bus respectifs.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Les bus quitteront Fatima \u00e0 l\u2019heure pr\u00e9vue, c\u2019est pourquoi il est demand\u00e9 aux participants de se pr\u00e9senter 20 minutes avant l\u2019heure de d\u00e9part, au parc 12 conform\u00e9ment aux instructions pr\u00e9c\u00e9dentes.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>De fa\u00e7on \u00e0 ce que personne ne perde un avion ou un train dans les villes d\u2019arriv\u00e9e, aucun retard au d\u00e9part de Fatima ne pourra \u00eatre tol\u00e9r\u00e9.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>L\u2019Organisation ne pourra pas se responsabiliser pour les d\u00e9sagr\u00e9ments des participants qui auront perdu leur bus, du fait d\u2019un \u00e9ventuel retard de leur part.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Les bus \u00e0 destination de l\u2019a\u00e9roport de Lisbonne s\u2019arr\u00eateront au Terminal\u00a01. Pour ceux qui prennent leur avion au Terminal 2, il suffira de prendre le shuttle interne de l\u2019a\u00e9roport.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Tous les autres participants \u00e0 destination de Lisbonne, sans avion pr\u00e9vu le 21 Juillet, pourront descendre \u00e0 la station Oriente pour pouvoir rejoindre le centre-ville (terminal de train, m\u00e9tro, bus et taxis). Eventuellement, certains pourront descendre \u00e0 l\u2019a\u00e9roport o\u00f9 se trouve \u00e9galement une station de m\u00e9tro.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Tous les participants \u00e0 destination de Porto pourront descendre \u00e0 l\u2019a\u00e9roport de la ville. Le transfert \u00e9ventuel vers la gare de Campanh\u00e3 (trains) devra se faire par moyens propres (m\u00e9tro ou taxi). Le d\u00e9part du bus de Fatima, dans ce cas particulier, prend en compte le temps de trajet entre l\u2019a\u00e9roport de Porto et la gare de Campanh\u00e3.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Avant de faire le mauvais parcours \u00e0 Fatima, voir ici les AVIS IMPORTANTS que l&#8217;\u00e9quipe d&#8217;organisation a pour vous! Il y a les avertissements g\u00e9n\u00e9raux, les avertissements du clerg\u00e9 et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/posts\/1653"}],"collection":[{"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/comments?post=1653"}],"version-history":[{"count":0,"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/posts\/1653\/revisions"}],"wp:attachment":[{"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/media?parent=1653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/categories?post=1653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fatima2018.equipes-notre-dame.com\/fr\/wp-json\/wp\/v2\/tags?post=1653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}